{"id":2681,"date":"2019-05-22T22:16:04","date_gmt":"2019-05-22T20:16:04","guid":{"rendered":"https:\/\/balsamico.shop\/de\/?p=2681"},"modified":"2019-05-23T08:05:25","modified_gmt":"2019-05-23T06:05:25","slug":"balsamico-verbraucher-tipps-im-ard-buffet","status":"publish","type":"post","link":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/","title":{"rendered":"Balsamico Verbraucher-Tipps im ARD Buffet"},"content":{"rendered":"<p>Im Lifestyle TV Magazin &#8222;<strong>ARD Buffet<\/strong>&#8220; (<a href=\"https:\/\/www.ardmediathek.de\/ard\/player\/Y3JpZDovL3N3ci5kZS9hZXgvbzExMTk4ODg\/tipps-zum-einkauf-von-essig\" target=\"_blank\" rel=\"noopener noreferrer\">zum Video<\/a>) wurden vergangene Woche einige Balsamico Essige <a href=\"https:\/\/www.ardmediathek.de\/ard\/player\/Y3JpZDovL3N3ci5kZS9hZXgvbzExMTk4ODg\/tipps-zum-einkauf-von-essig\" target=\"_blank\" rel=\"noopener noreferrer\">vorgestellt<\/a>. Moderator <a href=\"https:\/\/www.wienpahl-media.de\/holger-wienpahl-tv\/\" target=\"_blank\" rel=\"noopener noreferrer\">Holger Wienpahl<\/a> bespricht mit dem Ern\u00e4hrungsexperten <a href=\"https:\/\/www.hr-fernsehen.de\/sendungen-a-z\/service-trends\/experten\/dr-stephan-lueck,team-238.html\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Stephan L\u00fcck<\/a> worauf man es beim Kauf eines Balsamico Essigs ankommt. Vorgestellt wird gleich zu <a href=\"https:\/\/www.ardmediathek.de\/ard\/player\/Y3JpZDovL3N3ci5kZS9hZXgvbzExMTk4ODg\/tipps-zum-einkauf-von-essig\" target=\"_blank\" rel=\"noopener noreferrer\">Beginn der Sendung<\/a> unsere <strong>12 j\u00e4hrige <a href=\"https:\/\/balsamico.shop\/de\/produkt\/bernardo-tesori-silber-aceto-balsamico-tradizionale-di-modena-dop\/\">Silber &#8211; Serie &#8211; Bernardo Tesori &#8211; ein echter Aceto Balsamico Tradizionale di Modena D.O.P.<\/a><\/strong> gezeigt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"695\" class=\"alignnone wp-image-2682 size-full\" src=\"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-balsamico.jpg\" alt=\"ARD Buffet Balsamico\" srcset=\"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-balsamico.jpg 764w, https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-balsamico-300x273.jpg 300w, https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-balsamico-390x355.jpg 390w, https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-balsamico-600x546.jpg 600w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><br \/>\n<span style=\"font-size: xx-small;\"><em>Im Vordergrund, unser Bernardo Tesori (abgeklebt, soll keine Schleichwerbung sein) &#8211; <a href=\"https:\/\/balsamico.shop\/de\/produkt\/bernardo-tesori-silber-aceto-balsamico-tradizionale-di-modena-dop\/\">Silber-Edition<\/a> &#8211; ein echter Tradizionale &#8211; beige Kappe &#8211; mind. 12 Jahre gereift<\/em><\/span><\/p>\n<p>L\u00fcck geht bei der Pr\u00e4sentation der Essige darauf ein, dass die hohe Kunst bei einem Balsamico vom <strong>Tradizionale<\/strong> kommt. Denn nur der Aceto Balsamico Tradizionale ist ein kulinarisches Meisterwerk. Fehlt dieser Zusatz auf der Flasche sind wir in 99% der F\u00e4lle bei einem industriell hergestellten Essig-Gemisch, welche im besten Fall aus Traubenmost und Weinessig besteht und im schlechtesten Fall aus zahlreichen weiteren Zusatzstoffen wie dem &#8222;braunmacher&#8220; Farbstoff E150, Verdickungsmitteln, Zuckerzus\u00e4tze und anderen Lebensmittelchemikalien, von denen der Ern\u00e4hrungswissenschaftler in der Sendung abr\u00e4t.<\/p>\n<p>Dr. L\u00fcck gibt in seiner Funktion als Ern\u00e4hrungswissenschaftler den Verbrauchertipp in der Sendung:<\/p>\n<blockquote><p><em>Aber generell, muss man sich merken: Wenn E-Nummern auf so&#8217;nem Essig stehen, dann Finger weg! &#8211; <a href=\"https:\/\/www.ardmediathek.de\/ard\/player\/Y3JpZDovL3N3ci5kZS9hZXgvbzExMTk4ODg\/tipps-zum-einkauf-von-essig\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: yellow;\">Minute 1:45<\/span><\/a><\/em><\/p><\/blockquote>\n<p>Preislich erw\u00e4hnt L\u00fcck, dass ein echter Tradizionale zwischen 50 und 80 EUR liegt &#8211; und gesteht sich dabei selbst ein &#8211; &#8222;&#8230;<em>ganz ehrlich, das kauft kein Mensch<\/em>&#8220; &#8211; ganz so ist nun auch wieder nicht &#8211; preislich startet der Tradizionale bereits <a href=\"https:\/\/balsamico.shop\/de\/produkt\/malpighi-balsamico-affinato-aceto-tradizionale-12\/\">kurz \u00fcber 40 EUR<\/a> und geht bis weit <a href=\"https:\/\/balsamico.shop\/de\/produkt\/extravecchio-riserva-oro-abtm-dop-100-jahre\/\">\u00fcber 400 EUR f\u00fcr 100 ml<\/a>. Leisten k\u00f6nnen sich dieses lang gereifte Naturprodukt in der Tat nur Wenige, doch unsere bislang zufriedenen und mittlerweile weit \u00fcber 1.000 Kunden, so w\u00fcrde ich behaupten, sind immer menschlicher Natur gewesen \ud83d\ude42<\/p>\n<p>Einen <strong>echten Balsamico Tradizionale erkennen<\/strong> Sie an folgenden vier markanten Merkmalen:<\/p>\n<ul>\n<li>a) der Flaschenform &#8211; kleine bauchige 100 ml Flasche f\u00fcr einen Tradizionale &#8222;di Modena&#8220; und eine Tulpenform auch 100 ml f\u00fcr einen Tradizionale &#8222;di Reggio Emilia&#8220;.<\/li>\n<li>b) an der Zutatenliste &#8211; &#8222;mosto d&#8216; uva cotto&#8220; in Deutsch: &#8222;eingekochter Traubenmost&#8220; muss bei einem originalen Tradizionale di Modena mit <a href=\"http:\/\/www.casatella.it\/de\/die-erkennung-der-dop-geschutzte-ursprungsbezeichnung-fur-lebensmittel\/\" target=\"_blank\" rel=\"noopener noreferrer\">rot\/gelbem D.O.P. Siegel<\/a> hinten auf dem Etikett als einzige Zutat stehen. der Hinweis, dass nat\u00fcrliche Sulfite enthalten sind, ist normal &#8211; die kommen aus der Traubenschale.<\/li>\n<li>c) an der F\u00fcllmenge &#8211; ausschlie\u00dflich 100 ml f\u00fcr einen di Modena. Nur in der Region Reggio Emilia gibt es sehr sehr selten auch zul\u00e4ssige 250 ml Flaschen.<\/li>\n<li>d) einer eindeutigen Siegelnummer auf der Kappe bei einem di Modena. Die Farbe der Kappe ist einem 12 J\u00e4hrigen je nach Konsortium rot oder beige &#8211; in Ausnahmef\u00e4llen auch andersfarbig (z.B. bei fassreinen Abf\u00fcllungen der Acetaia Cristo). Bei einem 25 j\u00e4hrigen ist die Kappe ausschlie\u00dflich in Mattgold gehalten.<\/li>\n<\/ul>\n<p>Wir freuen uns \u00fcber die Berichterstattung und Aufkl\u00e4rung in Sachen Balsamico!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Lifestyle TV Magazin &#8222;ARD Buffet&#8220; (zum Video) wurden vergangene Woche einige Balsamico Essige vorgestellt. Moderator Holger Wienpahl bespricht mit dem Ern\u00e4hrungsexperten Dr. Stephan L\u00fcck worauf man es beim Kauf eines Balsamico Essigs ankommt. Vorgestellt wird gleich zu Beginn der Sendung unsere 12 j\u00e4hrige Silber &#8211; Serie &#8211; Bernardo Tesori &#8211; ein echter Aceto Balsamico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bdp_discover":false,"_bdp_news_title":"","_bdp_title_a":"","_bdp_title_b":"","_bdp_active_variant":"","_bdp_winning":false,"_bdp_rotate_days":0,"_bdp_recipe_yield":"","_bdp_recipe_ingredients":"","_bdp_recipe_steps":"","_bdp_recipe_prep_min":0,"_bdp_recipe_total_min":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Balsamico Verbraucher-Tipps im ARD Buffet &#187; Aceto Balsamico Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/\",\"url\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/\",\"name\":\"Balsamico Verbraucher-Tipps im ARD Buffet &#187; Aceto Balsamico Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ard-buffet-1.jpg\",\"datePublished\":\"2019-05-22T20:16:04+00:00\",\"dateModified\":\"2019-05-23T06:05:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ard-buffet-1.jpg\",\"contentUrl\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ard-buffet-1.jpg\",\"width\":818,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/balsamico-verbraucher-tipps-im-ard-buffet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Balsamico Verbraucher-Tipps im ARD Buffet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/\",\"name\":\"Aceto Balsamico Shop\",\"description\":\"Shop f\u00fcr Balsamico aus Modena &amp; Reggio Emilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#organization\",\"name\":\"Bernardo Tesori\",\"url\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/logo_bernardo.png\",\"contentUrl\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/logo_bernardo.png\",\"width\":278,\"height\":466,\"caption\":\"Bernardo Tesori\"},\"image\":{\"@id\":\"https:\\\/\\\/balsamico.shop\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Balsamico Verbraucher-Tipps im ARD Buffet &#187; Aceto Balsamico Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/","url":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/","name":"Balsamico Verbraucher-Tipps im ARD Buffet &#187; Aceto Balsamico Shop","isPartOf":{"@id":"https:\/\/balsamico.shop\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/#primaryimage"},"image":{"@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/#primaryimage"},"thumbnailUrl":"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-1.jpg","datePublished":"2019-05-22T20:16:04+00:00","dateModified":"2019-05-23T06:05:25+00:00","breadcrumb":{"@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/#primaryimage","url":"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-1.jpg","contentUrl":"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2019\/05\/ard-buffet-1.jpg","width":818,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/balsamico.shop\/de\/balsamico-verbraucher-tipps-im-ard-buffet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/balsamico.shop\/de\/"},{"@type":"ListItem","position":2,"name":"Balsamico Verbraucher-Tipps im ARD Buffet"}]},{"@type":"WebSite","@id":"https:\/\/balsamico.shop\/de\/#website","url":"https:\/\/balsamico.shop\/de\/","name":"Aceto Balsamico Shop","description":"Shop f\u00fcr Balsamico aus Modena &amp; Reggio Emilia","publisher":{"@id":"https:\/\/balsamico.shop\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balsamico.shop\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/balsamico.shop\/de\/#organization","name":"Bernardo Tesori","url":"https:\/\/balsamico.shop\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/balsamico.shop\/de\/#\/schema\/logo\/image\/","url":"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2016\/04\/logo_bernardo.png","contentUrl":"https:\/\/balsamico.shop\/de\/wp-content\/uploads\/2016\/04\/logo_bernardo.png","width":278,"height":466,"caption":"Bernardo Tesori"},"image":{"@id":"https:\/\/balsamico.shop\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/posts\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/comments?post=2681"}],"version-history":[{"count":9,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/posts\/2681\/revisions"}],"predecessor-version":[{"id":2694,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/posts\/2681\/revisions\/2694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/media\/2688"}],"wp:attachment":[{"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/categories?post=2681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/balsamico.shop\/de\/wp-json\/wp\/v2\/tags?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}